{"id":15935,"date":"2020-03-22T16:23:00","date_gmt":"2020-03-22T16:23:00","guid":{"rendered":"https:\/\/www.cosmed.fr\/newsletter\/newsletter-132\/"},"modified":"2021-04-09T07:21:59","modified_gmt":"2021-04-09T07:21:59","slug":"newsletter-132","status":"publish","type":"newsletter","link":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/","title":{"rendered":"Newsletter 132"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"199\" src=\"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg\" alt=\"newsletter\" class=\"wp-image-12716\" srcset=\"http:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg 810w, http:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1-300x74.jpg 300w, http:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1-768x189.jpg 768w, http:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1-600x147.jpg 600w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"container\">\n\n<div class=\"item-page\">\n<h2>Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res &#8211; les freins \u00e0 la production sont enfin lev\u00e9s !<\/h2>\n<p>Chers tous,<br \/>Face aux p\u00e9nuries en certaines mati\u00e8res premi\u00e8res signal\u00e9es par de nombreuses entreprises, Cosmed a propos\u00e9 aux autorit\u00e9s de tutelle de modifier l\u2019arr\u00eat\u00e9 du 13 mars 2020 afin de prendre en compte les difficult\u00e9s d\u2019approvisionnement qui limitaient le potentiel de fabrication des gels hydro-alcooliques par la fili\u00e8re cosm\u00e9tique.<br \/>C&#8217;est chose faite! L\u2019arr\u00eat\u00e9 <a href=\"https:\/\/www.legifrance.gouv.fr\/eli\/arrete\/2020\/3\/20\/TREP2008113A\/jo\/texte\">du 20 mars 2020<\/a>, publi\u00e9 ce jour au JORF, prend effet imm\u00e9diatement.<\/p>\n<p>D\u00e9sormais, les industriels de la cosm\u00e9tique peuvent recourir \u00e0 un large choix de g\u00e9lifiants et d\u2019humectants, ainsi que plusieurs cat\u00e9gories d\u2019alcool. En outre, sur les 4 formules agr\u00e9\u00e9es dans ces dispositions d\u00e9rogatoires, 2 peuvent \u00eatre r\u00e9alis\u00e9es sans eau oxyg\u00e9n\u00e9e. Les modalit\u00e9s d&#8217;exemption des obligations d\u00e9claratives (Symmbad, Synapse\u2026) sont conserv\u00e9es.<\/p>\n<p>Lib\u00e9r\u00e9 des risques de p\u00e9nurie de mati\u00e8res premi\u00e8res, vous pouvez d\u00e9sormais mettre \u00e0 disposition du march\u00e9 vos possibilit\u00e9s de fabrication. Les besoins sont immenses et pressants.<br \/>En tant que co-r\u00e9dacteur des \u00e9l\u00e9ments techniques de cet arr\u00eat\u00e9, Cosmed vous accompagne pour toute question li\u00e9e \u00e0 son application.<\/p>\n<p>Jean Marc GIROUX<br \/>Pr\u00e9sident<\/p>\n<p><em>Remerciements : Cosmed tient \u00e0 remercier chaleureusement les industriels, adh\u00e9rents ou pas, ainsi que les Administrateurs et toute l\u2019Equipe, qui se sont mobilis\u00e9s sans rel\u00e2che pour \u00e9laborer ces solutions en un temps record.\u00a0 Nous remercions \u00e9galement l\u2019Administration de son \u00e9coute et sa r\u00e9activit\u00e9 dans la situation actuelle. Avec une publication de l\u2019arr\u00eat\u00e9 en moins de 48 h, les freins \u00e0 la production sont enfin lev\u00e9s.<\/em><\/p>\n<\/div><\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-15935","newsletter","type-newsletter","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Newsletter 132 - Cosmed production gel hydro alcoolique<\/title>\n<meta name=\"description\" content=\"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newsletter 132 - Cosmed production gel hydro alcoolique\" \/>\n<meta property=\"og:description\" content=\"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmed\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T07:21:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/\",\"url\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/\",\"name\":\"Newsletter 132 - Cosmed production gel hydro alcoolique\",\"isPartOf\":{\"@id\":\"https:\/\/www.cosmed.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg\",\"datePublished\":\"2020-03-22T16:23:00+00:00\",\"dateModified\":\"2021-04-09T07:21:59+00:00\",\"description\":\"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !\",\"breadcrumb\":{\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage\",\"url\":\"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg\",\"contentUrl\":\"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cosmed.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletters\",\"item\":\"http:\/\/www.cosmed.fr\/newsletter\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsletter 132\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cosmed.fr\/#website\",\"url\":\"https:\/\/www.cosmed.fr\/\",\"name\":\"Cosmed\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cosmed.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newsletter 132 - Cosmed production gel hydro alcoolique","description":"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/","og_locale":"en_US","og_type":"article","og_title":"Newsletter 132 - Cosmed production gel hydro alcoolique","og_description":"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !","og_url":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/","og_site_name":"Cosmed","article_modified_time":"2021-04-09T07:21:59+00:00","og_image":[{"url":"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/","url":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/","name":"Newsletter 132 - Cosmed production gel hydro alcoolique","isPartOf":{"@id":"https:\/\/www.cosmed.fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage"},"image":{"@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg","datePublished":"2020-03-22T16:23:00+00:00","dateModified":"2021-04-09T07:21:59+00:00","description":"Gel hydro-alcoolique : ruptures de mati\u00e8re premi\u00e8res - les freins \u00e0 la production sont enfin lev\u00e9s !","breadcrumb":{"@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#primaryimage","url":"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg","contentUrl":"https:\/\/www.cosmed.fr\/app\/uploads\/2021\/01\/tetiere-cosmed-newsletter-1.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/www.cosmed.fr\/en\/newsletter\/newsletter-132\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cosmed.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Newsletters","item":"http:\/\/www.cosmed.fr\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Newsletter 132"}]},{"@type":"WebSite","@id":"https:\/\/www.cosmed.fr\/#website","url":"https:\/\/www.cosmed.fr\/","name":"Cosmed","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cosmed.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/www.cosmed.fr\/en\/wp-json\/wp\/v2\/newsletter\/15935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.cosmed.fr\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"http:\/\/www.cosmed.fr\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"wp:attachment":[{"href":"http:\/\/www.cosmed.fr\/en\/wp-json\/wp\/v2\/media?parent=15935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}